{"id":1385,"date":"2019-04-17T12:37:05","date_gmt":"2019-04-17T11:37:05","guid":{"rendered":"https:\/\/tentech.nl\/?page_id=1385"},"modified":"2019-09-13T12:36:36","modified_gmt":"2019-09-13T11:36:36","slug":"constructies-waterreservoir","status":"publish","type":"page","link":"https:\/\/tentech.nl\/fr\/en-lightweight-reservoirs-from-sketch-to-realisation\/","title":{"rendered":"(EN) Lightweight reservoirs, from sketch to realisation"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-fr\">D\u00e9sol\u00e9, cet article est seulement disponible en <a href=\"https:\/\/tentech.nl\/en\/wp-json\/wp\/v2\/pages\/1385\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"EN\">EN<\/a> et <a href=\"https:\/\/tentech.nl\/nl\/wp-json\/wp\/v2\/pages\/1385\" class=\"qtranxs-available-language-link qtranxs-available-language-link-nl\" title=\"NL\">NL<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>D\u00e9sol\u00e9, cet article est seulement disponible en EN et NL.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/landingpage.php","meta":{"footnotes":""},"class_list":["post-1385","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lichtgewicht waterreservoirs van schets tot realisatie<\/title>\n<meta name=\"description\" content=\"Tentech is gespecialiseerd in het ontwerpen en bedenken van lichtgewicht constructies voor de overkapping van een waterreservoir.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tentech.nl\/lichtgewicht-waterreservoirs-van-schets-tot-realisatie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lichtgewicht waterreservoirs van schets tot realisatie\" \/>\n<meta property=\"og:description\" content=\"Tentech is gespecialiseerd in het ontwerpen en bedenken van lichtgewicht constructies voor de overkapping van een waterreservoir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tentech.nl\/lichtgewicht-waterreservoirs-van-schets-tot-realisatie\/\" \/>\n<meta property=\"og:site_name\" content=\"Tentech\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-13T11:36:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tentech.nl\/wp-content\/uploads\/2019\/03\/Waterreservoir-Tentech.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tentech.nl\\\/lichtgewicht-waterreservoirs-van-schets-tot-realisatie\\\/\",\"url\":\"https:\\\/\\\/tentech.nl\\\/lichtgewicht-waterreservoirs-van-schets-tot-realisatie\\\/\",\"name\":\"Lichtgewicht waterreservoirs van schets tot realisatie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tentech.nl\\\/#website\"},\"datePublished\":\"2019-04-17T11:37:05+00:00\",\"dateModified\":\"2019-09-13T11:36:36+00:00\",\"description\":\"Tentech is gespecialiseerd in het ontwerpen en bedenken van lichtgewicht constructies voor de overkapping van een waterreservoir.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tentech.nl\\\/lichtgewicht-waterreservoirs-van-schets-tot-realisatie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tentech.nl\\\/lichtgewicht-waterreservoirs-van-schets-tot-realisatie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tentech.nl\\\/lichtgewicht-waterreservoirs-van-schets-tot-realisatie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tentech.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lichtgewicht waterreservoirs van schets tot realisatie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tentech.nl\\\/#website\",\"url\":\"https:\\\/\\\/tentech.nl\\\/\",\"name\":\"Tentech\",\"description\":\"ontwerp- en adviesbureau voor lichtgewicht bouwen\",\"publisher\":{\"@id\":\"https:\\\/\\\/tentech.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tentech.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tentech.nl\\\/#organization\",\"name\":\"Tentech B.V.\",\"url\":\"https:\\\/\\\/tentech.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/tentech.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tentech.nl\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Tentech-Utrecht-Design-and-Engineering-Lightweight-Structures.png\",\"contentUrl\":\"https:\\\/\\\/tentech.nl\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Tentech-Utrecht-Design-and-Engineering-Lightweight-Structures.png\",\"width\":415,\"height\":101,\"caption\":\"Tentech B.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/tentech.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lichtgewicht waterreservoirs van schets tot realisatie","description":"Tentech is gespecialiseerd in het ontwerpen en bedenken van lichtgewicht constructies voor de overkapping van een waterreservoir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tentech.nl\/lichtgewicht-waterreservoirs-van-schets-tot-realisatie\/","og_locale":"fr_FR","og_type":"article","og_title":"Lichtgewicht waterreservoirs van schets tot realisatie","og_description":"Tentech is gespecialiseerd in het ontwerpen en bedenken van lichtgewicht constructies voor de overkapping van een waterreservoir.","og_url":"https:\/\/tentech.nl\/lichtgewicht-waterreservoirs-van-schets-tot-realisatie\/","og_site_name":"Tentech","article_modified_time":"2019-09-13T11:36:36+00:00","og_image":[{"url":"https:\/\/tentech.nl\/wp-content\/uploads\/2019\/03\/Waterreservoir-Tentech.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tentech.nl\/lichtgewicht-waterreservoirs-van-schets-tot-realisatie\/","url":"https:\/\/tentech.nl\/lichtgewicht-waterreservoirs-van-schets-tot-realisatie\/","name":"Lichtgewicht waterreservoirs van schets tot realisatie","isPartOf":{"@id":"https:\/\/tentech.nl\/#website"},"datePublished":"2019-04-17T11:37:05+00:00","dateModified":"2019-09-13T11:36:36+00:00","description":"Tentech is gespecialiseerd in het ontwerpen en bedenken van lichtgewicht constructies voor de overkapping van een waterreservoir.","breadcrumb":{"@id":"https:\/\/tentech.nl\/lichtgewicht-waterreservoirs-van-schets-tot-realisatie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tentech.nl\/lichtgewicht-waterreservoirs-van-schets-tot-realisatie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tentech.nl\/lichtgewicht-waterreservoirs-van-schets-tot-realisatie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tentech.nl\/"},{"@type":"ListItem","position":2,"name":"Lichtgewicht waterreservoirs van schets tot realisatie"}]},{"@type":"WebSite","@id":"https:\/\/tentech.nl\/#website","url":"https:\/\/tentech.nl\/","name":"Tentech","description":"ontwerp- en adviesbureau voor lichtgewicht bouwen","publisher":{"@id":"https:\/\/tentech.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tentech.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/tentech.nl\/#organization","name":"Tentech B.V.","url":"https:\/\/tentech.nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tentech.nl\/#\/schema\/logo\/image\/","url":"https:\/\/tentech.nl\/wp-content\/uploads\/2019\/02\/Tentech-Utrecht-Design-and-Engineering-Lightweight-Structures.png","contentUrl":"https:\/\/tentech.nl\/wp-content\/uploads\/2019\/02\/Tentech-Utrecht-Design-and-Engineering-Lightweight-Structures.png","width":415,"height":101,"caption":"Tentech B.V."},"image":{"@id":"https:\/\/tentech.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tentech.nl\/fr\/wp-json\/wp\/v2\/pages\/1385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tentech.nl\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tentech.nl\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tentech.nl\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tentech.nl\/fr\/wp-json\/wp\/v2\/comments?post=1385"}],"version-history":[{"count":10,"href":"https:\/\/tentech.nl\/fr\/wp-json\/wp\/v2\/pages\/1385\/revisions"}],"predecessor-version":[{"id":1560,"href":"https:\/\/tentech.nl\/fr\/wp-json\/wp\/v2\/pages\/1385\/revisions\/1560"}],"wp:attachment":[{"href":"https:\/\/tentech.nl\/fr\/wp-json\/wp\/v2\/media?parent=1385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}